{"id":772,"date":"2011-09-21T09:33:40","date_gmt":"2011-09-21T07:33:40","guid":{"rendered":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2011\/09\/affiche-festival-soisson-en-scaisne.jpg"},"modified":"2011-09-21T09:33:40","modified_gmt":"2011-09-21T07:33:40","slug":"affiche-festival-soisson-en-scaisne-2","status":"inherit","type":"attachment","link":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/2011\/09\/21\/migration-de-nos-charmantes-petites-abeilles-dans-laisne\/affiche-festival-soisson-en-scaisne-2\/","title":{"rendered":"affiche festival soisson en sc&rsquo;aisne"},"author":3,"comment_status":"closed","ping_status":"open","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2011\/09\/affiche-festival-soisson-en-scaisne.jpg'><img width=\"209\" height=\"300\" src=\"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2011\/09\/affiche-festival-soisson-en-scaisne-209x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2011\/09\/affiche-festival-soisson-en-scaisne-209x300.jpg 209w, http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2011\/09\/affiche-festival-soisson-en-scaisne.jpg 259w\" sizes=\"(max-width: 209px) 100vw, 209px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":"259","height":"371","hwstring_small":"height='96' width='67'","file":"2011\/09\/affiche-festival-soisson-en-scaisne.jpg","sizes":{"thumbnail":{"file":"affiche-festival-soisson-en-scaisne-150x150.jpg","width":"150","height":"150","source_url":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2011\/09\/affiche-festival-soisson-en-scaisne-150x150.jpg"},"medium":{"file":"affiche-festival-soisson-en-scaisne-209x300.jpg","width":"209","height":"300","source_url":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2011\/09\/affiche-festival-soisson-en-scaisne-209x300.jpg"},"full":{"file":"affiche-festival-soisson-en-scaisne.jpg","width":259,"height":371,"mime_type":"image\/jpeg","source_url":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2011\/09\/affiche-festival-soisson-en-scaisne.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":""}},"post":769,"source_url":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2011\/09\/affiche-festival-soisson-en-scaisne.jpg","_links":{"self":[{"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/media\/772"}],"collection":[{"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/media"}],"about":[{"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/comments?post=772"}]}}