{"id":3392,"date":"2016-05-30T18:10:58","date_gmt":"2016-05-30T16:10:58","guid":{"rendered":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/?p=3392"},"modified":"2016-05-30T18:12:32","modified_gmt":"2016-05-30T16:12:32","slug":"j-4-mois-6e-edition-du-festival-cesarts-fete-la-planete","status":"publish","type":"post","link":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/2016\/05\/30\/j-4-mois-6e-edition-du-festival-cesarts-fete-la-planete\/","title":{"rendered":"J- 4 MOIS : 6e \u00e9dition du FESTIVAL C\u00c9SARTS F\u00caTE LA PLANETE !"},"content":{"rendered":"<p style=\"text-align: center;\"><a href=\"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2016\/05\/FESTIV-2016-BANDEAU.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-3393 aligncenter\" title=\"FESTIV 2016 BANDEAU\" src=\"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2016\/05\/FESTIV-2016-BANDEAU-300x149.jpg\" alt=\"\" width=\"300\" height=\"149\" srcset=\"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2016\/05\/FESTIV-2016-BANDEAU-300x149.jpg 300w, http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2016\/05\/FESTIV-2016-BANDEAU.jpg 795w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #008000;\">Nous avons besoin de vous !<\/span><\/p>\n<p>Vous avez aim\u00e9 l\u2019\u00e9dition 2015 ?  Vous allez adorer celle de 2016 ! Mais vous n\u2019\u00eates pas sans savoir qu\u2019en  ces temps difficiles de restrictions budg\u00e9taires, o\u00f9 nombre de  festivals tendent \u00e0 dispara\u00eetre ou voient leurs dotations se r\u00e9duire,  plus que jamais<span style=\"color: #800080;\"> il faut se battre pour maintenir l\u2019acc\u00e8s \u00e0 tous \u00e0 la  culture et \u00e0 l\u2019\u00e9ducation \u00e0 l\u2019environnement sur notre territoire<\/span>! Alors si nous voulons maintenir cette ann\u00e9e encore<span style=\"color: #800080;\"> la gratuit\u00e9<\/span> \u00e0  l\u2019entr\u00e9e et aux spectacles \u00e0 \u00ab<span style=\"text-decoration: underline;\"><span style=\"color: #0000ff;\">C\u00e9sarts f\u00eate la plan\u00e8te<\/span><\/span>\u00bb il nous faut  trouver de nouveaux <span style=\"color: #800080;\">soutiens financiers<\/span> !<\/p>\n<div>\n<p style=\"text-align: center;\"><span style=\"color: #ff0000;\">Vous pouvez nous aider, contribuer \u00e0 soutenir notre initiative \u00e9co-citoyenne :<br \/>\nOui, mais comment ? Au moins de 2 fa\u00e7ons :<\/span><\/p>\n<p><span style=\"color: #339966;\">&#8211; Avant le festival : nous sommes \u00e0 la recherche d\u2019annonceurs d\u00e9sirant  gagner en visibilit\u00e9 gr\u00e2ce \u00e0 l\u2019achat d\u2019encarts publicitaires dans le  flyer\/programme du festival (\u00e9dit\u00e9e \u00e0 + de 20 000 exemplaires), alors si  vous connaissez des entreprises, des artisans ou commer\u00e7ants qui sont  int\u00e9ress\u00e9s, CONTACTEZ NOUS VITE au 06 45 71 84 38 ou par mail :  pilepoilcompagnie@orange.fr ! Vos suggestions seront les bienvenues !<\/span><\/p>\n<p><span style=\"color: #3366ff;\">&#8211; Pendant le festival : Nous sommes \u00e9galement \u00e0 la recherche de  volontaires, de gentilles petites mains pour nous aider le samedi 24  et\/ou le dimanche 25 septembre et \u00e0 faire de cette journ\u00e9e un moment  inoubliable!<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ff6600;\">Merci \u00e0 tous !<\/span><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Nous avons besoin de vous ! Vous avez aim\u00e9 l\u2019\u00e9dition 2015 ? Vous allez adorer celle de 2016 ! Mais vous n\u2019\u00eates pas sans savoir qu\u2019en ces temps difficiles de restrictions budg\u00e9taires, o\u00f9 nombre de festivals tendent \u00e0 dispara\u00eetre ou voient leurs dotations se r\u00e9duire, plus que jamais il faut se battre pour maintenir l\u2019acc\u00e8s [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/posts\/3392"}],"collection":[{"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/comments?post=3392"}],"version-history":[{"count":6,"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/posts\/3392\/revisions"}],"predecessor-version":[{"id":3398,"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/posts\/3392\/revisions\/3398"}],"wp:attachment":[{"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/media?parent=3392"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/categories?post=3392"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/tags?post=3392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}