{"id":3433,"date":"2016-09-01T10:03:05","date_gmt":"2016-09-01T08:03:05","guid":{"rendered":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/?p=3433"},"modified":"2016-09-01T10:03:05","modified_gmt":"2016-09-01T08:03:05","slug":"la-page-evenement-du-festival-est-creee","status":"publish","type":"post","link":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/2016\/09\/01\/la-page-evenement-du-festival-est-creee\/","title":{"rendered":"La page  \u00e9v\u00e8nement du festival est cr\u00e9\u00e9e !"},"content":{"rendered":"<p style=\"text-align: center;\"><span style=\"color: #800080;\">OYE OYE ! Faites place \u00e0 la page \u00e9v\u00e8nement de la 6e \u00e9dition du Festival C\u00e9sarts f\u00eate la plan\u00e8te ! Sans vous, cette journ\u00e9e n&rsquo;aurait pas lieu&#8230; Alors n&rsquo;h\u00e9sitez pas \u00e0 liker, \u00e0 partager, \u00e0 inviter vos amis ! On compte sur vous !<\/span><\/p>\n<p style=\"text-align: center;\">Cliquez sur le visuel :<\/p>\n<p><a href=\"https:\/\/www.facebook.com\/events\/676757959156296\/\"><img decoding=\"async\" loading=\"lazy\" class=\"alignnone size-medium wp-image-3434 aligncenter\" src=\"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2016\/09\/cesart-300x172.png\" alt=\"cesart\" width=\"300\" height=\"172\" srcset=\"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2016\/09\/cesart-300x172.png 300w, http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2016\/09\/cesart.png 425w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>OYE OYE ! Faites place \u00e0 la page \u00e9v\u00e8nement de la 6e \u00e9dition du Festival C\u00e9sarts f\u00eate la plan\u00e8te ! Sans vous, cette journ\u00e9e n&rsquo;aurait pas lieu&#8230; Alors n&rsquo;h\u00e9sitez pas \u00e0 liker, \u00e0 partager, \u00e0 inviter vos amis ! On compte sur vous ! Cliquez sur le visuel :<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/posts\/3433"}],"collection":[{"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/comments?post=3433"}],"version-history":[{"count":1,"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/posts\/3433\/revisions"}],"predecessor-version":[{"id":3435,"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/posts\/3433\/revisions\/3435"}],"wp:attachment":[{"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/media?parent=3433"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/categories?post=3433"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/tags?post=3433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}