{"id":3767,"date":"2017-05-15T11:34:46","date_gmt":"2017-05-15T09:34:46","guid":{"rendered":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/?p=3767"},"modified":"2017-05-15T11:34:46","modified_gmt":"2017-05-15T09:34:46","slug":"nouvelle-escale-francilienne","status":"publish","type":"post","link":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/2017\/05\/15\/nouvelle-escale-francilienne\/","title":{"rendered":"Nouvelle escale francilienne !"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter  wp-image-3768\" src=\"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2017\/05\/LOGO-FESTIVAL-ZERO-GACHIS.jpg\" alt=\"LOGO FESTIVAL ZERO GACHIS\" width=\"413\" height=\"288\" srcset=\"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2017\/05\/LOGO-FESTIVAL-ZERO-GACHIS.jpg 533w, http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2017\/05\/LOGO-FESTIVAL-ZERO-GACHIS-300x209.jpg 300w\" sizes=\"(max-width: 413px) 100vw, 413px\" \/><span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #800080;\">Notre festival itin\u00e9rant pose ses valises dans les Hauts-de-Seine dans le cadre de la<span style=\"color: #008000;\"> semaine du d\u00e9veloppement durable<\/span> organis\u00e9e par la Ville de <span style=\"color: #008000;\">Clichy<\/span> !<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<img decoding=\"async\" loading=\"lazy\" class=\"aligncenter  wp-image-3769\" src=\"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2017\/05\/18268256_1476992685685954_2969776183262264131_n.jpg\" alt=\"18268256_1476992685685954_2969776183262264131_n\" width=\"681\" height=\"252\" srcset=\"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2017\/05\/18268256_1476992685685954_2969776183262264131_n.jpg 960w, http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2017\/05\/18268256_1476992685685954_2969776183262264131_n-300x111.jpg 300w, http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2017\/05\/18268256_1476992685685954_2969776183262264131_n-768x284.jpg 768w, http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2017\/05\/18268256_1476992685685954_2969776183262264131_n-800x296.jpg 800w\" sizes=\"(max-width: 681px) 100vw, 681px\" \/><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #800080;\">Nous intervenons le <span style=\"color: #008000;\">mercredi 17 mai<\/span> dans le Conservatoire L\u00e9o Delibes de Clichy-la-Garenne.<\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #ff0000;\">Au programme :<\/span><\/p>\n<p><span style=\"color: #800080;\">RDV \u00e0 <span style=\"color: #008000;\">14h45<\/span> pour une repr\u00e9sentation du spectacle \u00ab <span style=\"color: #008000;\">G\u00e2chis-bouzouk<\/span> \u00bb \u00e0 destination de 200 enfants des centres de loisirs de la ville et des visites de l&rsquo;exposition \u00ab stop au gaspi \u00bb.<\/span><\/p>\n<p><span style=\"color: #008000;\">Le programme de la semaine est <span style=\"text-decoration: underline; color: #800080;\"><a style=\"color: #800080; text-decoration: underline;\" href=\"http:\/\/www.ville-clichy.fr\/actualite\/1378\/19-actualite.htm\">ici <\/a><\/span>!<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>. Notre festival itin\u00e9rant pose ses valises dans les Hauts-de-Seine dans le cadre de la semaine du d\u00e9veloppement durable organis\u00e9e par la Ville de Clichy ! . . Nous intervenons le mercredi 17 mai dans le Conservatoire L\u00e9o Delibes de Clichy-la-Garenne. . Au programme : RDV \u00e0 14h45 pour une repr\u00e9sentation du spectacle \u00ab G\u00e2chis-bouzouk [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/posts\/3767"}],"collection":[{"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/comments?post=3767"}],"version-history":[{"count":3,"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/posts\/3767\/revisions"}],"predecessor-version":[{"id":3772,"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/posts\/3767\/revisions\/3772"}],"wp:attachment":[{"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/media?parent=3767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/categories?post=3767"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/tags?post=3767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}