{"id":4279,"date":"2018-04-12T10:28:29","date_gmt":"2018-04-12T08:28:29","guid":{"rendered":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/?p=4279"},"modified":"2018-04-12T10:28:29","modified_gmt":"2018-04-12T08:28:29","slug":"retour-sur-les-representations-du-dimanche-8-avril","status":"publish","type":"post","link":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/2018\/04\/12\/retour-sur-les-representations-du-dimanche-8-avril\/","title":{"rendered":"Retour sur les repr\u00e9sentations du dimanche 8 avril !"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter  wp-image-4280\" src=\"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2018\/04\/IMG_7329-2-R30.jpg\" alt=\"IMG_7329 (2) R30\" width=\"433\" height=\"265\" srcset=\"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2018\/04\/IMG_7329-2-R30.jpg 1536w, http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2018\/04\/IMG_7329-2-R30-300x184.jpg 300w, http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2018\/04\/IMG_7329-2-R30-768x471.jpg 768w, http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2018\/04\/IMG_7329-2-R30-800x490.jpg 800w\" sizes=\"(max-width: 433px) 100vw, 433px\" \/><\/p>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p style=\"text-align: left;\"><span style=\"color: #800080;\">Formidable dimanche \u00e0 <span style=\"color: #008000;\">Bourg-la-Reine<\/span> !<\/span><br \/>\n<span style=\"color: #800080;\">\u00ab\u00a0Sous les pav\u00e9s la nature\u00a0\u00bb au <span style=\"color: #008000;\">salon Vert-Avril<\/span> ! <\/span><br \/>\n<span style=\"color: #800080;\">Les 2 repr\u00e9sentations ensoleill\u00e9es des <span style=\"color: #008000;\">Rippetout<\/span> ont fait le plein de rire et de spectateurs (250) au milieu des jolies fleurs et des oies ! Tous ont repris en choeur notre slogan \u00e0 la mode 68 : \u00ab\u00a0<span style=\"color: #008000;\">pollution t&rsquo;es foutue les Rippetout sont dans la rue !<\/span> \u00ab\u00a0<\/span><br \/>\n<span style=\"color: #800080;\"> Une belle affluence pour parler de recyclage \u00ab\u00a0version champ\u00eatre\u00a0\u00bb, d&rsquo;hydromadaires et d&rsquo;\u00e9nergie positive dans la bonne humeur et l&rsquo;hum<span class=\"m_3076409556497936871text_exposed_show\">our, gr\u00e2ce \u00e0 la super-\u00e9quipe d&rsquo;organisation durable de la<span style=\"color: #008000;\"> Ville de Bourg-la-Reine<\/span>, sous la direction de Laurence ! Merci ! Merci ! Merci \u00e0 toutes et tous de nous avoir permis de semer \u00e0 tout vent de petites graines de <span style=\"color: #008000;\">sensibilisation<\/span> \u00e0 la <span style=\"color: #008000;\">protection<\/span> de notre environnement, qui nous l&rsquo;esp\u00e9rons germerons bien vite dans le coeur de tous les visiteurs&#8230; Nous avons pass\u00e9 un super moment en votre compagnie&#8230;<\/span><\/span><\/p>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter  wp-image-4281\" src=\"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2018\/04\/MONTAGE-PHOTO-CHAUD-DEVANT-CAMILLE-2.jpg\" alt=\"MONTAGE PHOTO CHAUD DEVANT CAMILLE (2)\" width=\"376\" height=\"387\" srcset=\"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2018\/04\/MONTAGE-PHOTO-CHAUD-DEVANT-CAMILLE-2.jpg 916w, http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2018\/04\/MONTAGE-PHOTO-CHAUD-DEVANT-CAMILLE-2-291x300.jpg 291w, http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2018\/04\/MONTAGE-PHOTO-CHAUD-DEVANT-CAMILLE-2-768x791.jpg 768w, http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2018\/04\/MONTAGE-PHOTO-CHAUD-DEVANT-CAMILLE-2-583x600.jpg 583w\" sizes=\"(max-width: 376px) 100vw, 376px\" \/><\/p>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p><span class=\"m_3076409556497936871text_exposed_show\" style=\"color: #000080;\">Petit retour en images de la folle journ\u00e9e de dimanche. Chaude ambiance et affluence record aux <span style=\"color: #ff0000;\">RANDODURABLES<\/span> \u00e0 la <span style=\"color: #ff0000;\">ferme de Viltain<\/span>, 300 spectateurs de tous \u00e2ges ont assist\u00e9 et particip\u00e9 \u00e0 notre spectacle sur le <span style=\"color: #ff0000;\">r\u00e9chauffement climatique<\/span> ! Merci pour toutes ces cascades de rires ! Merci \u00e0 la m\u00e9t\u00e9o de nous avoir permis de jouer jusqu&rsquo;au bout ! Merci au public d&rsquo;\u00eatre rest\u00e9 malgr\u00e9 le temps incertain (le vent \u00e9tait de la partie et un peu la pluie) merci \u00e0 toute l&rsquo;\u00e9quipe de la <span style=\"color: #ff0000;\">Communaut\u00e9 Paris-Saclay<\/span>, merci \u00e0 Antoine Balzeau notre scientifique pal\u00e9oanthropologue pr\u00e9f\u00e9r\u00e9, pour son inoubliable et brillante interpr\u00e9tation de sa majest\u00e9 le soleil ! Merci \u00e0 la\u00a0<span style=\"color: #ff0000;\"><a id=\"m_3076409556497936871LPlnk652092\" class=\"m_3076409556497936871profileLink\" style=\"color: #ff0000;\" href=\"https:\/\/www.facebook.com\/coccinelle.aseptpoints?fref=mentions\" target=\"_blank\" data-saferedirecturl=\"https:\/\/www.google.com\/url?hl=fr&amp;q=https:\/\/www.facebook.com\/coccinelle.aseptpoints?fref%3Dmentions&amp;source=gmail&amp;ust=1523605637110000&amp;usg=AFQjCNG7nxbnksby1D25lMQQxbb39WiP3w\">Coccinelle \u00c0 Sept Points<\/a><\/span>\u00a0notre porte bonheur ! Merci \u00e0\u00a0<span style=\"color: #ff0000;\"><a id=\"m_3076409556497936871LPlnk604422\" class=\"m_3076409556497936871profileLink\" style=\"color: #ff0000;\" href=\"https:\/\/www.facebook.com\/camille.labarthe?fref=mentions\" target=\"_blank\" data-saferedirecturl=\"https:\/\/www.google.com\/url?hl=fr&amp;q=https:\/\/www.facebook.com\/camille.labarthe?fref%3Dmentions&amp;source=gmail&amp;ust=1523605637110000&amp;usg=AFQjCNH5Hm15MMHzULhP2ZxdTn8JRTc9YQ\">Camille Labarthe<\/a><\/span>\u00a0notre d\u00e9licieuse Ang\u00e8le \u00ab\u00a0Mary Poppins\u00a0\u00bb tout terrain et \u00e0 super-<span style=\"color: #ff0000;\">Janique<\/span> pour sa r\u00e9gie fa\u00e7on Mc Gyver !<\/span><\/p>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter  wp-image-4282\" src=\"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2018\/04\/20180408_175215-2-r50.jpg\" alt=\"20180408_175215 (2) r50\" width=\"497\" height=\"258\" srcset=\"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2018\/04\/20180408_175215-2-r50.jpg 1808w, http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2018\/04\/20180408_175215-2-r50-300x156.jpg 300w, http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2018\/04\/20180408_175215-2-r50-768x398.jpg 768w, http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2018\/04\/20180408_175215-2-r50-800x415.jpg 800w\" sizes=\"(max-width: 497px) 100vw, 497px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>. Formidable dimanche \u00e0 Bourg-la-Reine ! \u00ab\u00a0Sous les pav\u00e9s la nature\u00a0\u00bb au salon Vert-Avril ! Les 2 repr\u00e9sentations ensoleill\u00e9es des Rippetout ont fait le plein de rire et de spectateurs (250) au milieu des jolies fleurs et des oies ! Tous ont repris en choeur notre slogan \u00e0 la mode 68 : \u00ab\u00a0pollution t&rsquo;es foutue [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/posts\/4279"}],"collection":[{"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/comments?post=4279"}],"version-history":[{"count":4,"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/posts\/4279\/revisions"}],"predecessor-version":[{"id":4286,"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/posts\/4279\/revisions\/4286"}],"wp:attachment":[{"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/media?parent=4279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/categories?post=4279"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/tags?post=4279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}