{"id":4525,"date":"2019-03-26T18:59:34","date_gmt":"2019-03-26T17:59:34","guid":{"rendered":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/?p=4525"},"modified":"2019-03-26T19:03:48","modified_gmt":"2019-03-26T18:03:48","slug":"cest-parti-pour-la-grande-tournee-nationale-de-printemps","status":"publish","type":"post","link":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/2019\/03\/26\/cest-parti-pour-la-grande-tournee-nationale-de-printemps\/","title":{"rendered":"C&rsquo;est parti pour la grande tourn\u00e9e nationale de printemps\u00a0!"},"content":{"rendered":"<p><span style=\"color: #1d2129;\"><span style=\"font-family: Helvetica, Arial, sans-serif;\"><span style=\"font-size: medium;\"><b>3 mois intenses de sensibilisation \u00e0 la transition \u00e9cologique et \u00e0 l&rsquo;\u00e9ducation au d\u00e9veloppement durable \u00e0 la rencontre des territoires\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0 \u00a0 et de leurs habitants,\u00a0pour donner envie \u00e0 tout le monde de se bouger,\u00a0\u00a0\u00a0\u00a0 de devenir acteur, d&rsquo;adopter un mode de vie \u00ab\u00e9co-responsable ! \u00a0 \u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0 \u00a0 Il y a urgence\u00a0! <\/b><\/span><\/span><\/span><\/p>\n<p><span style=\"color: #993366;\"><span style=\"font-family: Helvetica, Arial, sans-serif;\"><span style=\"font-size: x-large;\"><b>\u00a0\u00a0\u00a0 du samedi 30 mars au 27 juin 2019 <\/b><\/span><\/span><\/span><b> <\/b><\/p>\n<p><span style=\"color: #8ccf00;\">\u00a0\u00a0\u00a0\u00a0 <span style=\"font-family: Helvetica, Arial, sans-serif;\"><span style=\"font-size: x-large;\"><b>45 repr\u00e9sentations exceptionnelles\u00a0<\/b><\/span><\/span><\/span><b> <\/b><\/p>\n<p><span style=\"color: #4c4c4c;\"><span style=\"font-family: Verdana, sans-serif;\"><span style=\"font-size: large;\"><b>dans 24 d\u00e9partements en France et en Wallonie<\/b><\/span><\/span><\/span><\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-4526 aligncenter\" src=\"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2019\/03\/tourn\u00e9e-printemps-avril-2019-300x282.jpg\" alt=\"tourn\u00e9e printemps avril 2019\" width=\"300\" height=\"282\" srcset=\"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2019\/03\/tourn\u00e9e-printemps-avril-2019-300x282.jpg 300w, http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2019\/03\/tourn\u00e9e-printemps-avril-2019-768x722.jpg 768w, http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2019\/03\/tourn\u00e9e-printemps-avril-2019-638x600.jpg 638w, http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2019\/03\/tourn\u00e9e-printemps-avril-2019.jpg 916w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><span style=\"color: #1d2129;\"><span style=\"font-family: Helvetica, Arial, sans-serif;\"><span style=\"font-size: large;\"><b>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Au programme :\u00a0<\/b><\/span><\/span><\/span><\/p>\n<p><span style=\"color: #006b6b;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: x-large;\"><b>Retrouvez nos 10 spectacles pour voir la vie en vert <\/b><\/span><\/span><\/span><\/p>\n<p><span style=\"color: #006b6b;\">\u00a0\u00a0 \u00a0 \u00a0 \u00a0 <span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: large;\"><b>sur sc\u00e8ne, en festival ou en arts de la rue, dans la nature <\/b><\/span><\/span><\/span><\/p>\n<p><span style=\"color: #006b6b;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: large;\"><b>et basculez avec nous <\/b><\/span><\/span><\/span><strong><span style=\"color: #006b6b;\"><span style=\"font-family: Times New Roman, serif;\"><span style=\"font-size: large;\"><b>dans la belle saison\u00a0! <\/b><\/span><\/span><\/span><\/strong><\/p>\n<p><span style=\"font-family: Times New Roman, serif;\"><b>Toutes les \u00e9tapes\u00a0 en cliquant <a href=\"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/agenda-des-tournees\/\" target=\"_blank\">ici\u00a0 <\/a>:<br \/>\n<\/b><\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>3 mois intenses de sensibilisation \u00e0 la transition \u00e9cologique et \u00e0 l&rsquo;\u00e9ducation au d\u00e9veloppement durable \u00e0 la rencontre des territoires\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0 \u00a0 et de leurs habitants,\u00a0pour donner envie \u00e0 tout le monde de se bouger,\u00a0\u00a0\u00a0\u00a0 de devenir acteur, d&rsquo;adopter un mode de vie \u00ab\u00e9co-responsable ! \u00a0 \u00a0 \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00a0 \u00a0 \u00a0 Il y a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/posts\/4525"}],"collection":[{"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/comments?post=4525"}],"version-history":[{"count":23,"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/posts\/4525\/revisions"}],"predecessor-version":[{"id":4549,"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/posts\/4525\/revisions\/4549"}],"wp:attachment":[{"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/media?parent=4525"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/categories?post=4525"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/tags?post=4525"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}