{"id":4802,"date":"2019-07-02T10:54:24","date_gmt":"2019-07-02T08:54:24","guid":{"rendered":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/?p=4802"},"modified":"2019-07-02T10:54:24","modified_gmt":"2019-07-02T08:54:24","slug":"clap-de-fin-pour-la-grande-tournee-de-printemps","status":"publish","type":"post","link":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/2019\/07\/02\/clap-de-fin-pour-la-grande-tournee-de-printemps\/","title":{"rendered":"clap de fin pour la grande tourn\u00e9e de printemps !"},"content":{"rendered":"<p>Et voil\u00e0 que le bout du bout de la saison pointe son nez, et c\u2019est avec beaucoup d\u2019\u00e9motions joyeuses, merveilleuses et clownesques que nous cl\u00f4turons notre p\u00e9riple \u00e9ducatif dans les territoires :<br \/>\n\u00e7a repr\u00e9sente au total :<br \/>\n<span style=\"color: #993366;\">du samedi 30 mars au 27 juin 2019<\/span><br \/>\n10 spectacles pour voir la vie en vert<br \/>\nsur sc\u00e8ne, en festival ou en arts de la rue, dans la nature, dans un palais des congr\u00e8s dans des lieux improbables&#8230;<br \/>\n26 d\u00e9partements en France et en Belgique visit\u00e9s<br \/>\n<span style=\"color: #ff00ff;\">15400 spectateurs<\/span><br \/>\n<span style=\"color: #0000ff;\">53 dates<\/span><br \/>\n<span style=\"color: #008080;\">85 repr\u00e9sentations exceptionnelles<\/span><br \/>\n<span style=\"color: #808000;\">15000 kms parcourus<\/span><br \/>\nbravo \u00e0 notre belle \u00e9quipe de com\u00e9diennes, com\u00e9diens et techniciens au top ! sans oublier Janique, notre petite f\u00e9e de l&rsquo;organisation de la tourn\u00e9e&#8230;Alex, Paul et Romane \u00e0 la technique&#8230;merci d&rsquo;avoir contribu\u00e9 au succ\u00e8s de cette tourn\u00e9e !<img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-4803 aligncenter\" src=\"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2019\/07\/0001-Copie-63-300x282.jpg\" alt=\"0001 - Copie (63)\" width=\"300\" height=\"282\" srcset=\"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2019\/07\/0001-Copie-63-300x282.jpg 300w, http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2019\/07\/0001-Copie-63-768x722.jpg 768w, http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2019\/07\/0001-Copie-63-638x600.jpg 638w, http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2019\/07\/0001-Copie-63.jpg 916w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Nous ramenons dans nos valises des tonnes de sourires, de rire et d&rsquo;huile de coude et tellement de belles rencontres, de moments intenses, d&rsquo;\u00e9motions qui ne s&rsquo;ach\u00e8tent pas !<br \/>\nen esp\u00e9rant juste avoir \u00e9t\u00e9 de petits colibris convaincants !<br \/>\n3 mois denses de sensibilisation de terrain \u00e0 la transition \u00e9cologique, \u00e0 l&rsquo;\u00e9ducation au d\u00e9veloppement durable, \u00e0 la biodiversit\u00e9, au changement climatique, au tri des d\u00e9chets, au fl\u00e9au du plastique dans les oc\u00e9ans&#8230; une riche aventure \u00e0 la rencontre des territoires et de leurs habitants de tous \u00e2ges, pour donner envie \u00e0 tout le monde de se bouger, de devenir acteur, d&rsquo;adopter vite un mode de vie plus respirable ! Il y a urgence !<br \/>\nMerci aux organisateurs de nous avoir accueillis, et maintenant cap sur le festival d&rsquo;Avignon !<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-4804 aligncenter\" src=\"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2019\/07\/MONTAGE-PHOTO-PALAIS-DES-CONGRES-AIX-300x165.jpg\" alt=\"MONTAGE PHOTO PALAIS DES CONGRES AIX\" width=\"300\" height=\"165\" srcset=\"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2019\/07\/MONTAGE-PHOTO-PALAIS-DES-CONGRES-AIX-300x165.jpg 300w, http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2019\/07\/MONTAGE-PHOTO-PALAIS-DES-CONGRES-AIX-768x422.jpg 768w, http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2019\/07\/MONTAGE-PHOTO-PALAIS-DES-CONGRES-AIX-800x440.jpg 800w, http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2019\/07\/MONTAGE-PHOTO-PALAIS-DES-CONGRES-AIX.jpg 913w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Et voil\u00e0 que le bout du bout de la saison pointe son nez, et c\u2019est avec beaucoup d\u2019\u00e9motions joyeuses, merveilleuses et clownesques que nous cl\u00f4turons notre p\u00e9riple \u00e9ducatif dans les territoires : \u00e7a repr\u00e9sente au total : du samedi 30 mars au 27 juin 2019 10 spectacles pour voir la vie en vert sur sc\u00e8ne, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/posts\/4802"}],"collection":[{"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/comments?post=4802"}],"version-history":[{"count":4,"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/posts\/4802\/revisions"}],"predecessor-version":[{"id":4808,"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/posts\/4802\/revisions\/4808"}],"wp:attachment":[{"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/media?parent=4802"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/categories?post=4802"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/tags?post=4802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}