{"id":4865,"date":"2019-10-15T16:09:42","date_gmt":"2019-10-15T14:09:42","guid":{"rendered":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/?p=4865"},"modified":"2019-10-15T16:09:42","modified_gmt":"2019-10-15T14:09:42","slug":"sauvons-nos-aliments","status":"publish","type":"post","link":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/2019\/10\/15\/sauvons-nos-aliments\/","title":{"rendered":"Sauvons nos aliments\u00a0!!!"},"content":{"rendered":"<p><span style=\"font-family: Times New Roman, serif;\">Demain le 16 octobre c&rsquo;est la journ\u00e9e nationale de lutte contre le gaspillage. <\/span><span style=\"font-family: Times New Roman, serif;\">Pile Poil, fid\u00e8le \u00e0 sa mission, y participe\u00a0 activement \u00e0 Charleville-M\u00e9zi\u00e8res <\/span><span style=\"font-family: Times New Roman, serif;\">dans les Ardennes avec \u00ab\u00a0G\u00e2chisbouzouk\u00a0\u00bb. <\/span><span style=\"font-family: Times New Roman, serif;\">Le spectacle se joue \u00e0 la Maison de la Culture MCL ma Boh\u00ebme <\/span><span style=\"font-family: Times New Roman, serif;\">aux c\u00f4t\u00e9s du syndicat Valodea et c&rsquo;est d\u00e9j\u00e0 complet\u00a0!<\/span><\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-4867 aligncenter\" src=\"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2019\/10\/thumbnail_image001-300x211.jpg\" alt=\"thumbnail_image001\" width=\"300\" height=\"211\" srcset=\"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2019\/10\/thumbnail_image001-300x211.jpg 300w, http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2019\/10\/thumbnail_image001-768x541.jpg 768w, http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2019\/10\/thumbnail_image001.jpg 794w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-4866 aligncenter\" src=\"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2019\/10\/MONTAGE-GACHIS-FERDI-ET-GASTON-300x275.jpg\" alt=\"MONTAGE GACHIS FERDI ET GASTON\" width=\"300\" height=\"275\" srcset=\"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2019\/10\/MONTAGE-GACHIS-FERDI-ET-GASTON-300x275.jpg 300w, http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2019\/10\/MONTAGE-GACHIS-FERDI-ET-GASTON-768x704.jpg 768w, http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2019\/10\/MONTAGE-GACHIS-FERDI-ET-GASTON-654x600.jpg 654w, http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-content\/uploads\/2019\/10\/MONTAGE-GACHIS-FERDI-ET-GASTON.jpg 890w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Demain le 16 octobre c&rsquo;est la journ\u00e9e nationale de lutte contre le gaspillage. Pile Poil, fid\u00e8le \u00e0 sa mission, y participe\u00a0 activement \u00e0 Charleville-M\u00e9zi\u00e8res dans les Ardennes avec \u00ab\u00a0G\u00e2chisbouzouk\u00a0\u00bb. Le spectacle se joue \u00e0 la Maison de la Culture MCL ma Boh\u00ebme aux c\u00f4t\u00e9s du syndicat Valodea et c&rsquo;est d\u00e9j\u00e0 complet\u00a0!<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/posts\/4865"}],"collection":[{"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/comments?post=4865"}],"version-history":[{"count":3,"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/posts\/4865\/revisions"}],"predecessor-version":[{"id":4870,"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/posts\/4865\/revisions\/4870"}],"wp:attachment":[{"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/media?parent=4865"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/categories?post=4865"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.pilepoilplanete.com\/POILOBLOG\/wp-json\/wp\/v2\/tags?post=4865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}